{"id":4465,"date":"2026-03-17T12:16:45","date_gmt":"2026-03-17T12:16:45","guid":{"rendered":"https:\/\/corporacionjimenezmana.com\/?p=4465"},"modified":"2026-03-17T13:39:23","modified_gmt":"2026-03-17T13:39:23","slug":"memoria-rsc-2025","status":"publish","type":"post","link":"https:\/\/corporacionjimenezmana.com\/fr\/memoria-rsc-2025\/","title":{"rendered":"Memoria RSC 2025"},"content":{"rendered":"<p class=\"wp-block-paragraph\">En <strong>Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a<\/strong> siempre decimos que \u00abel prop\u00f3sito hace el camino\u00bb, y al echar la vista atr\u00e1s a este 2025, no podemos estar m\u00e1s orgullosos del camino que hemos construido juntos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy compartimos con todos vosotros nuestra <strong>Memoria de Responsabilidad Social Corporativa 2025<\/strong>. Esta m\u00e1s que un informe de datos, es un \u00e1lbum de fotos y recuerdos de todo lo que hemos logrado gracias a la ilusi\u00f3n y la generosidad de cada una de las personas que forman esta gran familia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este 2025 nos ha dejado momentos que nos llenan el coraz\u00f3n. A trav\u00e9s de estas p\u00e1ginas, ver\u00e9is reflejado lo que somos: <strong>equipo, confianza y esp\u00edritu de servicio<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestra Directora de RSC, <strong>Reyes Jim\u00e9nez-Ma\u00f1a<\/strong>, lo resume con estas palabras llenas de cari\u00f1o:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em>\u00abMe hace much\u00edsima ilusi\u00f3n celebrar con vosotros los logros alcanzados. Nada de esto habr\u00eda sido posible sin el apoyo de todo el equipo de la Corporaci\u00f3n. Juntos, con una participaci\u00f3n de casi el 30%, hemos demostrado que cuidar de las personas y de nuestro entorno es lo que de verdad nos mueve.\u00bb<\/em><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Pero esto no se para aqu\u00ed. De cara a este nuevo a\u00f1o, queremos seguir construyendo un entorno m\u00e1s humano. Nuestra bandera para el 2026 ser\u00e1 la alegr\u00eda de <strong>darse a los dem\u00e1s<\/strong>. Queremos que nuestra generosidad sea el motor para cumplir nuestro nuevo lema: <strong>#CuidarEsElegirUnFuturoMejor<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os invitamos a hojear nuestra memoria, a sentiros parte de cada proyecto, porque al final, <strong>este camino lo haces t\u00fa.<\/strong> Tambi\u00e9n te invitamos a ver nuestra noticia de <a href=\"https:\/\/www.linkedin.com\/company\/5376077\/admin\/page-posts\/published\/\">LinkedIn <\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/corporacionjimenezmana.com\/wp-content\/uploads\/2026\/03\/MEMORIA-RSC-2025.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Contenu embarqu\u00e9 MEMORIA RSC 2025.\"><\/object><a id=\"wp-block-file--media-7aeec3c0-a398-44ad-a31a-94e071ddaadd\" href=\"https:\/\/corporacionjimenezmana.com\/wp-content\/uploads\/2026\/03\/MEMORIA-RSC-2025.pdf\">MEMORIA RSC 2025<\/a><a href=\"https:\/\/corporacionjimenezmana.com\/wp-content\/uploads\/2026\/03\/MEMORIA-RSC-2025.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-7aeec3c0-a398-44ad-a31a-94e071ddaadd\">Descarga<\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>En Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a siempre decimos que \u00abel prop\u00f3sito hace el camino\u00bb, y al echar la vista atr\u00e1s a este 2025, no podemos estar m\u00e1s orgullosos del camino que hemos construido juntos. Hoy compartimos con todos vosotros nuestra Memoria de Responsabilidad Social Corporativa 2025. Esta m\u00e1s que un informe de datos, es un \u00e1lbum de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4467,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-4465","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rsc"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Memoria RSC 2025 - Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/corporacionjimenezmana.com\/fr\/memoria-rsc-2025\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Memoria RSC 2025 - Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a\" \/>\n<meta property=\"og:description\" content=\"En Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a siempre decimos que \u00abel prop\u00f3sito hace el camino\u00bb, y al echar la vista atr\u00e1s a este 2025, no podemos estar m\u00e1s orgullosos del camino que hemos construido juntos. Hoy compartimos con todos vosotros nuestra Memoria de Responsabilidad Social Corporativa 2025. Esta m\u00e1s que un informe de datos, es un \u00e1lbum de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/corporacionjimenezmana.com\/fr\/memoria-rsc-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-17T12:16:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-17T13:39:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/corporacionjimenezmana.com\/wp-content\/uploads\/2026\/03\/PORTADA-RSC.png\" \/>\n\t<meta property=\"og:image:width\" content=\"565\" \/>\n\t<meta property=\"og:image:height\" content=\"187\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ana_CJM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ana_CJM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/memoria-rsc-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/memoria-rsc-2025\\\/\"},\"author\":{\"name\":\"Ana_CJM\",\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/#\\\/schema\\\/person\\\/79f6bf54f1afc014ee30d26697bd224d\"},\"headline\":\"Memoria RSC 2025\",\"datePublished\":\"2026-03-17T12:16:45+00:00\",\"dateModified\":\"2026-03-17T13:39:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/memoria-rsc-2025\\\/\"},\"wordCount\":275,\"publisher\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/memoria-rsc-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/PORTADA-RSC.png\",\"articleSection\":[\"RSC\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/memoria-rsc-2025\\\/\",\"url\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/memoria-rsc-2025\\\/\",\"name\":\"Memoria RSC 2025 - Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/memoria-rsc-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/memoria-rsc-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/PORTADA-RSC.png\",\"datePublished\":\"2026-03-17T12:16:45+00:00\",\"dateModified\":\"2026-03-17T13:39:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/memoria-rsc-2025\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/corporacionjimenezmana.com\\\/memoria-rsc-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/memoria-rsc-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/PORTADA-RSC.png\",\"contentUrl\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/PORTADA-RSC.png\",\"width\":565,\"height\":187},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/memoria-rsc-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Memoria RSC 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/#website\",\"url\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/\",\"name\":\"Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a\",\"description\":\"Grupo de empresas familiar l\u00edder en la distribuci\u00f3n de recambios de veh\u00edculos. Desde su fundaci\u00f3n en 1936, ha demostrado una gran capacidad de adaptaci\u00f3n y crecimiento, ampliando sus actividades dentro y fuera del sector de la movilidad, consolid\u00e1ndose como un grupo empresarial con m\u00faltiples l\u00edneas de negocio.\",\"publisher\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/#organization\",\"name\":\"Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a\",\"url\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/imagotipo-Corporacion-Jimenez-Mana.svg\",\"contentUrl\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/imagotipo-Corporacion-Jimenez-Mana.svg\",\"width\":425,\"height\":94,\"caption\":\"Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a\"},\"image\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/corpjimenezmana\\\/?viewAsMember=true\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/#\\\/schema\\\/person\\\/79f6bf54f1afc014ee30d26697bd224d\",\"name\":\"Ana_CJM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e63e46543d6b7e0b7dc215b9d4a080da2328755463d201cae9932c5b21162524?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e63e46543d6b7e0b7dc215b9d4a080da2328755463d201cae9932c5b21162524?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e63e46543d6b7e0b7dc215b9d4a080da2328755463d201cae9932c5b21162524?s=96&d=mm&r=g\",\"caption\":\"Ana_CJM\"},\"url\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/fr\\\/author\\\/ana_cjm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Memoria RSC 2025 - Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/corporacionjimenezmana.com\/fr\/memoria-rsc-2025\/","og_locale":"fr_FR","og_type":"article","og_title":"Memoria RSC 2025 - Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a","og_description":"En Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a siempre decimos que \u00abel prop\u00f3sito hace el camino\u00bb, y al echar la vista atr\u00e1s a este 2025, no podemos estar m\u00e1s orgullosos del camino que hemos construido juntos. Hoy compartimos con todos vosotros nuestra Memoria de Responsabilidad Social Corporativa 2025. Esta m\u00e1s que un informe de datos, es un \u00e1lbum de [&hellip;]","og_url":"https:\/\/corporacionjimenezmana.com\/fr\/memoria-rsc-2025\/","og_site_name":"Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a","article_published_time":"2026-03-17T12:16:45+00:00","article_modified_time":"2026-03-17T13:39:23+00:00","og_image":[{"width":565,"height":187,"url":"https:\/\/corporacionjimenezmana.com\/wp-content\/uploads\/2026\/03\/PORTADA-RSC.png","type":"image\/png"}],"author":"Ana_CJM","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Ana_CJM","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/corporacionjimenezmana.com\/memoria-rsc-2025\/#article","isPartOf":{"@id":"https:\/\/corporacionjimenezmana.com\/memoria-rsc-2025\/"},"author":{"name":"Ana_CJM","@id":"https:\/\/corporacionjimenezmana.com\/#\/schema\/person\/79f6bf54f1afc014ee30d26697bd224d"},"headline":"Memoria RSC 2025","datePublished":"2026-03-17T12:16:45+00:00","dateModified":"2026-03-17T13:39:23+00:00","mainEntityOfPage":{"@id":"https:\/\/corporacionjimenezmana.com\/memoria-rsc-2025\/"},"wordCount":275,"publisher":{"@id":"https:\/\/corporacionjimenezmana.com\/#organization"},"image":{"@id":"https:\/\/corporacionjimenezmana.com\/memoria-rsc-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/corporacionjimenezmana.com\/wp-content\/uploads\/2026\/03\/PORTADA-RSC.png","articleSection":["RSC"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/corporacionjimenezmana.com\/memoria-rsc-2025\/","url":"https:\/\/corporacionjimenezmana.com\/memoria-rsc-2025\/","name":"Memoria RSC 2025 - Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a","isPartOf":{"@id":"https:\/\/corporacionjimenezmana.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/corporacionjimenezmana.com\/memoria-rsc-2025\/#primaryimage"},"image":{"@id":"https:\/\/corporacionjimenezmana.com\/memoria-rsc-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/corporacionjimenezmana.com\/wp-content\/uploads\/2026\/03\/PORTADA-RSC.png","datePublished":"2026-03-17T12:16:45+00:00","dateModified":"2026-03-17T13:39:23+00:00","breadcrumb":{"@id":"https:\/\/corporacionjimenezmana.com\/memoria-rsc-2025\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/corporacionjimenezmana.com\/memoria-rsc-2025\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/corporacionjimenezmana.com\/memoria-rsc-2025\/#primaryimage","url":"https:\/\/corporacionjimenezmana.com\/wp-content\/uploads\/2026\/03\/PORTADA-RSC.png","contentUrl":"https:\/\/corporacionjimenezmana.com\/wp-content\/uploads\/2026\/03\/PORTADA-RSC.png","width":565,"height":187},{"@type":"BreadcrumbList","@id":"https:\/\/corporacionjimenezmana.com\/memoria-rsc-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/corporacionjimenezmana.com\/"},{"@type":"ListItem","position":2,"name":"Memoria RSC 2025"}]},{"@type":"WebSite","@id":"https:\/\/corporacionjimenezmana.com\/#website","url":"https:\/\/corporacionjimenezmana.com\/","name":"Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a","description":"Grupo de empresas familiar l\u00edder en la distribuci\u00f3n de recambios de veh\u00edculos. Desde su fundaci\u00f3n en 1936, ha demostrado una gran capacidad de adaptaci\u00f3n y crecimiento, ampliando sus actividades dentro y fuera del sector de la movilidad, consolid\u00e1ndose como un grupo empresarial con m\u00faltiples l\u00edneas de negocio.","publisher":{"@id":"https:\/\/corporacionjimenezmana.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/corporacionjimenezmana.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/corporacionjimenezmana.com\/#organization","name":"Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a","url":"https:\/\/corporacionjimenezmana.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/corporacionjimenezmana.com\/#\/schema\/logo\/image\/","url":"https:\/\/corporacionjimenezmana.com\/wp-content\/uploads\/2024\/10\/imagotipo-Corporacion-Jimenez-Mana.svg","contentUrl":"https:\/\/corporacionjimenezmana.com\/wp-content\/uploads\/2024\/10\/imagotipo-Corporacion-Jimenez-Mana.svg","width":425,"height":94,"caption":"Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a"},"image":{"@id":"https:\/\/corporacionjimenezmana.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/corpjimenezmana\/?viewAsMember=true"]},{"@type":"Person","@id":"https:\/\/corporacionjimenezmana.com\/#\/schema\/person\/79f6bf54f1afc014ee30d26697bd224d","name":"Ana_CJM","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e63e46543d6b7e0b7dc215b9d4a080da2328755463d201cae9932c5b21162524?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e63e46543d6b7e0b7dc215b9d4a080da2328755463d201cae9932c5b21162524?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e63e46543d6b7e0b7dc215b9d4a080da2328755463d201cae9932c5b21162524?s=96&d=mm&r=g","caption":"Ana_CJM"},"url":"https:\/\/corporacionjimenezmana.com\/fr\/author\/ana_cjm\/"}]}},"_links":{"self":[{"href":"https:\/\/corporacionjimenezmana.com\/fr\/wp-json\/wp\/v2\/posts\/4465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corporacionjimenezmana.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corporacionjimenezmana.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corporacionjimenezmana.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/corporacionjimenezmana.com\/fr\/wp-json\/wp\/v2\/comments?post=4465"}],"version-history":[{"count":0,"href":"https:\/\/corporacionjimenezmana.com\/fr\/wp-json\/wp\/v2\/posts\/4465\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corporacionjimenezmana.com\/fr\/wp-json\/wp\/v2\/media\/4467"}],"wp:attachment":[{"href":"https:\/\/corporacionjimenezmana.com\/fr\/wp-json\/wp\/v2\/media?parent=4465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corporacionjimenezmana.com\/fr\/wp-json\/wp\/v2\/categories?post=4465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corporacionjimenezmana.com\/fr\/wp-json\/wp\/v2\/tags?post=4465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}