{"id":1926,"date":"2024-11-25T13:29:19","date_gmt":"2024-11-25T13:29:19","guid":{"rendered":"https:\/\/peachpuff-snail-755067.hostingersite.com\/?p=1926"},"modified":"2026-01-21T09:17:04","modified_gmt":"2026-01-21T09:17:04","slug":"pick-pack-systems-amplia-su-almacen-de-madrid-para-atender-al-crecimiento-de-sus-operaciones","status":"publish","type":"post","link":"https:\/\/corporacionjimenezmana.com\/en\/pick-pack-systems-amplia-su-almacen-de-madrid-para-atender-al-crecimiento-de-sus-operaciones\/","title":{"rendered":"Pick &amp; Pack Systems ampl\u00eda su almac\u00e9n de Madrid para atender al crecimiento de sus operaciones."},"content":{"rendered":"<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Pick &amp; Pack Systems ampl\u00eda su almac\u00e9n de Madrid ubicado en una zona estrat\u00e9gica con entrega hasta 3 veces al d\u00eda en el \u00e1rea central de Espa\u00f1a.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/pickpacksys.com\/\"><strong>Pick &amp; Pack Systems<\/strong><\/a>, operador log\u00edstico especializado en picking de alta velocidad, ha anunciado la ampliaci\u00f3n de su almac\u00e9n en Villaverde, Madrid. Ubicado en una zona estrat\u00e9gica dentro del primer anillo de la capital, esta instalaci\u00f3n permite la entrega de pedidos hasta tres veces al d\u00eda en el \u00e1rea central de Espa\u00f1a, facilitando una mayor eficiencia y rapidez para sus clientes, respondiendo as\u00ed a la demanda de nuevas colaboraciones. Con esta expansi\u00f3n, el espacio de <strong>Pick &amp; Pack<\/strong> en Villaverde suma ahora m\u00e1s de 45.000 metros cuadrados, consolidando su presencia en las principales ciudades de Espa\u00f1a, como Barcelona, Madrid y Sevilla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este crecimiento se alinea con el compromiso de <strong>Pick &amp; Pack<\/strong> de ofrecer a sus clientes una soluci\u00f3n integral, permiti\u00e9ndoles enfocarse en su actividad principal mientras el equipo se encarga de la log\u00edstica completa. <em>\u201cDebido a la alta demanda de servicios log\u00edsticos y al \u00e9xito del modelo de <strong>Pick &amp; Pack<\/strong>, en los pr\u00f3ximos tres a\u00f1os prevemos la apertura de dos nuevos almacenes para cubrir las crecientes necesidades de nuestros clientes<\/em>\u201d, comenta Luis Jim\u00e9nez, Gerente de <strong>Pick &amp; Pack Systems.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta ampliaci\u00f3n responde tanto al crecimiento de clientes actuales, muchos de los cuales son fabricantes que ampl\u00edan sus cadenas de producci\u00f3n, como a nuevas alianzas con distribuidores de sectores clave como automoci\u00f3n, climatizaci\u00f3n, el\u00e9ctrico y ferreter\u00eda. Estos clientes conf\u00edan en <strong>Pick &amp; Pack<\/strong> para optimizar sus operaciones log\u00edsticas en Espa\u00f1a, encontrando en ellos un aliado fundamental.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de sus servicios de almacenamiento, preparaci\u00f3n de pedidos, cross-docking, log\u00edstica inversa, transporte y distribuci\u00f3n, <strong>Pick &amp; Pack<\/strong> destaca por su l\u00ednea de externalizaci\u00f3n <strong>log\u00edstica in-house<\/strong>. Esta soluci\u00f3n permite a las empresas que desean mantener su propio almac\u00e9n contar con una mejora en productividad, organizaci\u00f3n, capacidad de crecimiento, y control de procesos, todo ellos acompa\u00f1ado de un aliado de confianza centrado en la misi\u00f3n de sus clientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con esta ampliaci\u00f3n y su apuesta por la expansi\u00f3n, <strong>Pick &amp; Pack<\/strong> refuerza su posici\u00f3n como socio estrat\u00e9gico en el sector log\u00edstico, proporcionando infraestructura y servicios para que sus clientes puedan desarrollar su negocio de manera eficiente y competitiva.<\/p>","protected":false},"excerpt":{"rendered":"<p>Pick &amp; Pack Systems ampl\u00eda su almac\u00e9n de Madrid ubicado en una zona estrat\u00e9gica con entrega hasta 3 veces al d\u00eda en el \u00e1rea central de Espa\u00f1a. Pick &amp; Pack Systems, operador log\u00edstico especializado en picking de alta velocidad, ha anunciado la ampliaci\u00f3n de su almac\u00e9n en Villaverde, Madrid. Ubicado en una zona estrat\u00e9gica dentro [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1927,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17,19],"tags":[],"class_list":["post-1926","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nota-de-prensa","category-lineas-de-negocio"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pick &amp; Pack Systems ampl\u00eda su almac\u00e9n de Madrid para atender al crecimiento de sus operaciones. - Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/corporacionjimenezmana.com\/en\/pick-pack-systems-amplia-su-almacen-de-madrid-para-atender-al-crecimiento-de-sus-operaciones\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pick &amp; Pack Systems ampl\u00eda su almac\u00e9n de Madrid para atender al crecimiento de sus operaciones. - Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a\" \/>\n<meta property=\"og:description\" content=\"Pick &amp; Pack Systems ampl\u00eda su almac\u00e9n de Madrid ubicado en una zona estrat\u00e9gica con entrega hasta 3 veces al d\u00eda en el \u00e1rea central de Espa\u00f1a. Pick &amp; Pack Systems, operador log\u00edstico especializado en picking de alta velocidad, ha anunciado la ampliaci\u00f3n de su almac\u00e9n en Villaverde, Madrid. Ubicado en una zona estrat\u00e9gica dentro [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/corporacionjimenezmana.com\/en\/pick-pack-systems-amplia-su-almacen-de-madrid-para-atender-al-crecimiento-de-sus-operaciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-25T13:29:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-21T09:17:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/corporacionjimenezmana.com\/wp-content\/uploads\/2025\/01\/image.png\" \/>\n\t<meta property=\"og:image:width\" content=\"709\" \/>\n\t<meta property=\"og:image:height\" content=\"501\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ana_CJM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ana_CJM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/pick-pack-systems-amplia-su-almacen-de-madrid-para-atender-al-crecimiento-de-sus-operaciones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/pick-pack-systems-amplia-su-almacen-de-madrid-para-atender-al-crecimiento-de-sus-operaciones\\\/\"},\"author\":{\"name\":\"Ana_CJM\",\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/#\\\/schema\\\/person\\\/79f6bf54f1afc014ee30d26697bd224d\"},\"headline\":\"Pick &amp; Pack Systems ampl\u00eda su almac\u00e9n de Madrid para atender al crecimiento de sus operaciones.\",\"datePublished\":\"2024-11-25T13:29:19+00:00\",\"dateModified\":\"2026-01-21T09:17:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/pick-pack-systems-amplia-su-almacen-de-madrid-para-atender-al-crecimiento-de-sus-operaciones\\\/\"},\"wordCount\":435,\"publisher\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/pick-pack-systems-amplia-su-almacen-de-madrid-para-atender-al-crecimiento-de-sus-operaciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/image.png\",\"articleSection\":[\"NOTAS DE PRENSA\",\"LINEAS DE NEGOCIO\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/pick-pack-systems-amplia-su-almacen-de-madrid-para-atender-al-crecimiento-de-sus-operaciones\\\/\",\"url\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/pick-pack-systems-amplia-su-almacen-de-madrid-para-atender-al-crecimiento-de-sus-operaciones\\\/\",\"name\":\"Pick &amp; Pack Systems ampl\u00eda su almac\u00e9n de Madrid para atender al crecimiento de sus operaciones. - Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/pick-pack-systems-amplia-su-almacen-de-madrid-para-atender-al-crecimiento-de-sus-operaciones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/pick-pack-systems-amplia-su-almacen-de-madrid-para-atender-al-crecimiento-de-sus-operaciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/image.png\",\"datePublished\":\"2024-11-25T13:29:19+00:00\",\"dateModified\":\"2026-01-21T09:17:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/pick-pack-systems-amplia-su-almacen-de-madrid-para-atender-al-crecimiento-de-sus-operaciones\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/corporacionjimenezmana.com\\\/pick-pack-systems-amplia-su-almacen-de-madrid-para-atender-al-crecimiento-de-sus-operaciones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/pick-pack-systems-amplia-su-almacen-de-madrid-para-atender-al-crecimiento-de-sus-operaciones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/image.png\",\"contentUrl\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/image.png\",\"width\":709,\"height\":501},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/pick-pack-systems-amplia-su-almacen-de-madrid-para-atender-al-crecimiento-de-sus-operaciones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pick &amp; Pack Systems ampl\u00eda su almac\u00e9n de Madrid para atender al crecimiento de sus operaciones.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/#website\",\"url\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/\",\"name\":\"Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a\",\"description\":\"Grupo de empresas familiar l\u00edder en la distribuci\u00f3n de recambios de veh\u00edculos. Desde su fundaci\u00f3n en 1936, ha demostrado una gran capacidad de adaptaci\u00f3n y crecimiento, ampliando sus actividades dentro y fuera del sector de la movilidad, consolid\u00e1ndose como un grupo empresarial con m\u00faltiples l\u00edneas de negocio.\",\"publisher\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/#organization\",\"name\":\"Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a\",\"url\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/imagotipo-Corporacion-Jimenez-Mana.svg\",\"contentUrl\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/imagotipo-Corporacion-Jimenez-Mana.svg\",\"width\":425,\"height\":94,\"caption\":\"Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a\"},\"image\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/corpjimenezmana\\\/?viewAsMember=true\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/#\\\/schema\\\/person\\\/79f6bf54f1afc014ee30d26697bd224d\",\"name\":\"Ana_CJM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e63e46543d6b7e0b7dc215b9d4a080da2328755463d201cae9932c5b21162524?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e63e46543d6b7e0b7dc215b9d4a080da2328755463d201cae9932c5b21162524?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e63e46543d6b7e0b7dc215b9d4a080da2328755463d201cae9932c5b21162524?s=96&d=mm&r=g\",\"caption\":\"Ana_CJM\"},\"url\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/en\\\/author\\\/ana_cjm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pick &amp; Pack Systems ampl\u00eda su almac\u00e9n de Madrid para atender al crecimiento de sus operaciones. - Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/corporacionjimenezmana.com\/en\/pick-pack-systems-amplia-su-almacen-de-madrid-para-atender-al-crecimiento-de-sus-operaciones\/","og_locale":"en_GB","og_type":"article","og_title":"Pick &amp; Pack Systems ampl\u00eda su almac\u00e9n de Madrid para atender al crecimiento de sus operaciones. - Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a","og_description":"Pick &amp; Pack Systems ampl\u00eda su almac\u00e9n de Madrid ubicado en una zona estrat\u00e9gica con entrega hasta 3 veces al d\u00eda en el \u00e1rea central de Espa\u00f1a. Pick &amp; Pack Systems, operador log\u00edstico especializado en picking de alta velocidad, ha anunciado la ampliaci\u00f3n de su almac\u00e9n en Villaverde, Madrid. Ubicado en una zona estrat\u00e9gica dentro [&hellip;]","og_url":"https:\/\/corporacionjimenezmana.com\/en\/pick-pack-systems-amplia-su-almacen-de-madrid-para-atender-al-crecimiento-de-sus-operaciones\/","og_site_name":"Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a","article_published_time":"2024-11-25T13:29:19+00:00","article_modified_time":"2026-01-21T09:17:04+00:00","og_image":[{"width":709,"height":501,"url":"https:\/\/corporacionjimenezmana.com\/wp-content\/uploads\/2025\/01\/image.png","type":"image\/png"}],"author":"Ana_CJM","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ana_CJM","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/corporacionjimenezmana.com\/pick-pack-systems-amplia-su-almacen-de-madrid-para-atender-al-crecimiento-de-sus-operaciones\/#article","isPartOf":{"@id":"https:\/\/corporacionjimenezmana.com\/pick-pack-systems-amplia-su-almacen-de-madrid-para-atender-al-crecimiento-de-sus-operaciones\/"},"author":{"name":"Ana_CJM","@id":"https:\/\/corporacionjimenezmana.com\/#\/schema\/person\/79f6bf54f1afc014ee30d26697bd224d"},"headline":"Pick &amp; Pack Systems ampl\u00eda su almac\u00e9n de Madrid para atender al crecimiento de sus operaciones.","datePublished":"2024-11-25T13:29:19+00:00","dateModified":"2026-01-21T09:17:04+00:00","mainEntityOfPage":{"@id":"https:\/\/corporacionjimenezmana.com\/pick-pack-systems-amplia-su-almacen-de-madrid-para-atender-al-crecimiento-de-sus-operaciones\/"},"wordCount":435,"publisher":{"@id":"https:\/\/corporacionjimenezmana.com\/#organization"},"image":{"@id":"https:\/\/corporacionjimenezmana.com\/pick-pack-systems-amplia-su-almacen-de-madrid-para-atender-al-crecimiento-de-sus-operaciones\/#primaryimage"},"thumbnailUrl":"https:\/\/corporacionjimenezmana.com\/wp-content\/uploads\/2025\/01\/image.png","articleSection":["NOTAS DE PRENSA","LINEAS DE NEGOCIO"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/corporacionjimenezmana.com\/pick-pack-systems-amplia-su-almacen-de-madrid-para-atender-al-crecimiento-de-sus-operaciones\/","url":"https:\/\/corporacionjimenezmana.com\/pick-pack-systems-amplia-su-almacen-de-madrid-para-atender-al-crecimiento-de-sus-operaciones\/","name":"Pick &amp; Pack Systems ampl\u00eda su almac\u00e9n de Madrid para atender al crecimiento de sus operaciones. - Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a","isPartOf":{"@id":"https:\/\/corporacionjimenezmana.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/corporacionjimenezmana.com\/pick-pack-systems-amplia-su-almacen-de-madrid-para-atender-al-crecimiento-de-sus-operaciones\/#primaryimage"},"image":{"@id":"https:\/\/corporacionjimenezmana.com\/pick-pack-systems-amplia-su-almacen-de-madrid-para-atender-al-crecimiento-de-sus-operaciones\/#primaryimage"},"thumbnailUrl":"https:\/\/corporacionjimenezmana.com\/wp-content\/uploads\/2025\/01\/image.png","datePublished":"2024-11-25T13:29:19+00:00","dateModified":"2026-01-21T09:17:04+00:00","breadcrumb":{"@id":"https:\/\/corporacionjimenezmana.com\/pick-pack-systems-amplia-su-almacen-de-madrid-para-atender-al-crecimiento-de-sus-operaciones\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/corporacionjimenezmana.com\/pick-pack-systems-amplia-su-almacen-de-madrid-para-atender-al-crecimiento-de-sus-operaciones\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/corporacionjimenezmana.com\/pick-pack-systems-amplia-su-almacen-de-madrid-para-atender-al-crecimiento-de-sus-operaciones\/#primaryimage","url":"https:\/\/corporacionjimenezmana.com\/wp-content\/uploads\/2025\/01\/image.png","contentUrl":"https:\/\/corporacionjimenezmana.com\/wp-content\/uploads\/2025\/01\/image.png","width":709,"height":501},{"@type":"BreadcrumbList","@id":"https:\/\/corporacionjimenezmana.com\/pick-pack-systems-amplia-su-almacen-de-madrid-para-atender-al-crecimiento-de-sus-operaciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/corporacionjimenezmana.com\/"},{"@type":"ListItem","position":2,"name":"Pick &amp; Pack Systems ampl\u00eda su almac\u00e9n de Madrid para atender al crecimiento de sus operaciones."}]},{"@type":"WebSite","@id":"https:\/\/corporacionjimenezmana.com\/#website","url":"https:\/\/corporacionjimenezmana.com\/","name":"Jim\u00e9nez Ma\u00f1a Corporation","description":"Leading family business group in the distribution of vehicle spare parts. Since its foundation in 1936, it has demonstrated a great capacity for adaptation and growth, expanding its activities inside and outside the mobility sector, consolidating itself as a business group with multiple lines of business.","publisher":{"@id":"https:\/\/corporacionjimenezmana.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/corporacionjimenezmana.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/corporacionjimenezmana.com\/#organization","name":"Jim\u00e9nez Ma\u00f1a Corporation","url":"https:\/\/corporacionjimenezmana.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/corporacionjimenezmana.com\/#\/schema\/logo\/image\/","url":"https:\/\/corporacionjimenezmana.com\/wp-content\/uploads\/2024\/10\/imagotipo-Corporacion-Jimenez-Mana.svg","contentUrl":"https:\/\/corporacionjimenezmana.com\/wp-content\/uploads\/2024\/10\/imagotipo-Corporacion-Jimenez-Mana.svg","width":425,"height":94,"caption":"Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a"},"image":{"@id":"https:\/\/corporacionjimenezmana.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/corpjimenezmana\/?viewAsMember=true"]},{"@type":"Person","@id":"https:\/\/corporacionjimenezmana.com\/#\/schema\/person\/79f6bf54f1afc014ee30d26697bd224d","name":"Ana_CJM","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/e63e46543d6b7e0b7dc215b9d4a080da2328755463d201cae9932c5b21162524?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e63e46543d6b7e0b7dc215b9d4a080da2328755463d201cae9932c5b21162524?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e63e46543d6b7e0b7dc215b9d4a080da2328755463d201cae9932c5b21162524?s=96&d=mm&r=g","caption":"Ana_CJM"},"url":"https:\/\/corporacionjimenezmana.com\/en\/author\/ana_cjm\/"}]}},"_links":{"self":[{"href":"https:\/\/corporacionjimenezmana.com\/en\/wp-json\/wp\/v2\/posts\/1926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corporacionjimenezmana.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corporacionjimenezmana.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corporacionjimenezmana.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/corporacionjimenezmana.com\/en\/wp-json\/wp\/v2\/comments?post=1926"}],"version-history":[{"count":0,"href":"https:\/\/corporacionjimenezmana.com\/en\/wp-json\/wp\/v2\/posts\/1926\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corporacionjimenezmana.com\/en\/wp-json\/wp\/v2\/media\/1927"}],"wp:attachment":[{"href":"https:\/\/corporacionjimenezmana.com\/en\/wp-json\/wp\/v2\/media?parent=1926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corporacionjimenezmana.com\/en\/wp-json\/wp\/v2\/categories?post=1926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corporacionjimenezmana.com\/en\/wp-json\/wp\/v2\/tags?post=1926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}