{"id":1916,"date":"2024-12-18T13:01:48","date_gmt":"2024-12-18T13:01:48","guid":{"rendered":"https:\/\/peachpuff-snail-755067.hostingersite.com\/?p=1916"},"modified":"2026-01-21T09:16:47","modified_gmt":"2026-01-21T09:16:47","slug":"premio-compromiso-con-la-sostenibilidad-en-la-posventa-ancera","status":"publish","type":"post","link":"https:\/\/corporacionjimenezmana.com\/en\/premio-compromiso-con-la-sostenibilidad-en-la-posventa-ancera\/","title":{"rendered":"Premio \u00abCompromiso con la Sostenibilidad en la Posventa\u00bb ANCERA"},"content":{"rendered":"<p class=\"wp-block-paragraph\">El pasado 17 de diciembre se celebraron en Ifema, Madrid los premios de ANCERA que premian los proyectos de sostenibilidad ambiental y social en el sector de la postventa de automoci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Asociaci\u00f3n Espa\u00f1ola de Proveedores de Automoci\u00f3n (SERNAUTO) y la Asociaci\u00f3n Nacional de Comerciantes de&nbsp;equipos, recambios, Neum\u00e1ticos y Accesorios para Automoci\u00f3n (ANCERA), junto con las asociaciones de talleres CETRAA y CONEPA , en colaboraci\u00f3n con Motortec Madrid, hicieron posible esta cuarta gala de los Premios Compromiso con la Sostenibilidad en la posventa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a recibi\u00f3 el premio en la categor\u00eda de \u00abImpacto en las personas\u00bb. Estamos muy orgullosos y muy agradecidos por este reconocimiento. Pensamos que todas las personas pueden ser verdaderos l\u00edderes que crecen personal y profesionalmente cuando orientan su trabajo con coherencia, autenticidad e integridad. De ese modo, pueden alcanzar la excelencia, el bienestar de la sociedad y la sostenibilidad de la empresa. Queremos expandir en nuestro entorno empresarial y social los tres elementos claves de nuestra cultura: prop\u00f3sito, misi\u00f3n y valores. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Corporaci\u00f3n cuidamos de las personas poni\u00e9ndolas en el centro. Seguiremos trabajando d\u00eda a d\u00eda para que esto sea posible.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><\/figure>","protected":false},"excerpt":{"rendered":"<p>El pasado 17 de diciembre se celebraron en Ifema, Madrid los premios de ANCERA que premian los proyectos de sostenibilidad ambiental y social en el sector de la postventa de automoci\u00f3n. La Asociaci\u00f3n Espa\u00f1ola de Proveedores de Automoci\u00f3n (SERNAUTO) y la Asociaci\u00f3n Nacional de Comerciantes de&nbsp;equipos, recambios, Neum\u00e1ticos y Accesorios para Automoci\u00f3n (ANCERA), junto con [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1919,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-1916","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rsc"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Premio &quot;Compromiso con la Sostenibilidad en la Posventa&quot; ANCERA - Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/corporacionjimenezmana.com\/en\/premio-compromiso-con-la-sostenibilidad-en-la-posventa-ancera\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Premio &quot;Compromiso con la Sostenibilidad en la Posventa&quot; ANCERA - Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a\" \/>\n<meta property=\"og:description\" content=\"El pasado 17 de diciembre se celebraron en Ifema, Madrid los premios de ANCERA que premian los proyectos de sostenibilidad ambiental y social en el sector de la postventa de automoci\u00f3n. La Asociaci\u00f3n Espa\u00f1ola de Proveedores de Automoci\u00f3n (SERNAUTO) y la Asociaci\u00f3n Nacional de Comerciantes de&nbsp;equipos, recambios, Neum\u00e1ticos y Accesorios para Automoci\u00f3n (ANCERA), junto con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/corporacionjimenezmana.com\/en\/premio-compromiso-con-la-sostenibilidad-en-la-posventa-ancera\/\" \/>\n<meta property=\"og:site_name\" content=\"Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-18T13:01:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-21T09:16:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/corporacionjimenezmana.com\/wp-content\/uploads\/2025\/01\/FOTO_FAMILIA_PREMIOS_COMPROMISO3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ana_CJM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ana_CJM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/premio-compromiso-con-la-sostenibilidad-en-la-posventa-ancera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/premio-compromiso-con-la-sostenibilidad-en-la-posventa-ancera\\\/\"},\"author\":{\"name\":\"Ana_CJM\",\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/#\\\/schema\\\/person\\\/79f6bf54f1afc014ee30d26697bd224d\"},\"headline\":\"Premio \u00abCompromiso con la Sostenibilidad en la Posventa\u00bb ANCERA\",\"datePublished\":\"2024-12-18T13:01:48+00:00\",\"dateModified\":\"2026-01-21T09:16:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/premio-compromiso-con-la-sostenibilidad-en-la-posventa-ancera\\\/\"},\"wordCount\":214,\"publisher\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/premio-compromiso-con-la-sostenibilidad-en-la-posventa-ancera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/FOTO_FAMILIA_PREMIOS_COMPROMISO3.png\",\"articleSection\":[\"RSC\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/premio-compromiso-con-la-sostenibilidad-en-la-posventa-ancera\\\/\",\"url\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/premio-compromiso-con-la-sostenibilidad-en-la-posventa-ancera\\\/\",\"name\":\"Premio \\\"Compromiso con la Sostenibilidad en la Posventa\\\" ANCERA - Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/premio-compromiso-con-la-sostenibilidad-en-la-posventa-ancera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/premio-compromiso-con-la-sostenibilidad-en-la-posventa-ancera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/FOTO_FAMILIA_PREMIOS_COMPROMISO3.png\",\"datePublished\":\"2024-12-18T13:01:48+00:00\",\"dateModified\":\"2026-01-21T09:16:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/premio-compromiso-con-la-sostenibilidad-en-la-posventa-ancera\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/corporacionjimenezmana.com\\\/premio-compromiso-con-la-sostenibilidad-en-la-posventa-ancera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/premio-compromiso-con-la-sostenibilidad-en-la-posventa-ancera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/FOTO_FAMILIA_PREMIOS_COMPROMISO3.png\",\"contentUrl\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/FOTO_FAMILIA_PREMIOS_COMPROMISO3.png\",\"width\":1500,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/premio-compromiso-con-la-sostenibilidad-en-la-posventa-ancera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Premio \u00abCompromiso con la Sostenibilidad en la Posventa\u00bb ANCERA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/#website\",\"url\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/\",\"name\":\"Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a\",\"description\":\"Grupo de empresas familiar l\u00edder en la distribuci\u00f3n de recambios de veh\u00edculos. Desde su fundaci\u00f3n en 1936, ha demostrado una gran capacidad de adaptaci\u00f3n y crecimiento, ampliando sus actividades dentro y fuera del sector de la movilidad, consolid\u00e1ndose como un grupo empresarial con m\u00faltiples l\u00edneas de negocio.\",\"publisher\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/#organization\",\"name\":\"Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a\",\"url\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/imagotipo-Corporacion-Jimenez-Mana.svg\",\"contentUrl\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/imagotipo-Corporacion-Jimenez-Mana.svg\",\"width\":425,\"height\":94,\"caption\":\"Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a\"},\"image\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/corpjimenezmana\\\/?viewAsMember=true\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/#\\\/schema\\\/person\\\/79f6bf54f1afc014ee30d26697bd224d\",\"name\":\"Ana_CJM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e63e46543d6b7e0b7dc215b9d4a080da2328755463d201cae9932c5b21162524?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e63e46543d6b7e0b7dc215b9d4a080da2328755463d201cae9932c5b21162524?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e63e46543d6b7e0b7dc215b9d4a080da2328755463d201cae9932c5b21162524?s=96&d=mm&r=g\",\"caption\":\"Ana_CJM\"},\"url\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/en\\\/author\\\/ana_cjm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Premio \"Compromiso con la Sostenibilidad en la Posventa\" ANCERA - Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/corporacionjimenezmana.com\/en\/premio-compromiso-con-la-sostenibilidad-en-la-posventa-ancera\/","og_locale":"en_GB","og_type":"article","og_title":"Premio \"Compromiso con la Sostenibilidad en la Posventa\" ANCERA - Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a","og_description":"El pasado 17 de diciembre se celebraron en Ifema, Madrid los premios de ANCERA que premian los proyectos de sostenibilidad ambiental y social en el sector de la postventa de automoci\u00f3n. La Asociaci\u00f3n Espa\u00f1ola de Proveedores de Automoci\u00f3n (SERNAUTO) y la Asociaci\u00f3n Nacional de Comerciantes de&nbsp;equipos, recambios, Neum\u00e1ticos y Accesorios para Automoci\u00f3n (ANCERA), junto con [&hellip;]","og_url":"https:\/\/corporacionjimenezmana.com\/en\/premio-compromiso-con-la-sostenibilidad-en-la-posventa-ancera\/","og_site_name":"Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a","article_published_time":"2024-12-18T13:01:48+00:00","article_modified_time":"2026-01-21T09:16:47+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/corporacionjimenezmana.com\/wp-content\/uploads\/2025\/01\/FOTO_FAMILIA_PREMIOS_COMPROMISO3.png","type":"image\/png"}],"author":"Ana_CJM","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ana_CJM","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/corporacionjimenezmana.com\/premio-compromiso-con-la-sostenibilidad-en-la-posventa-ancera\/#article","isPartOf":{"@id":"https:\/\/corporacionjimenezmana.com\/premio-compromiso-con-la-sostenibilidad-en-la-posventa-ancera\/"},"author":{"name":"Ana_CJM","@id":"https:\/\/corporacionjimenezmana.com\/#\/schema\/person\/79f6bf54f1afc014ee30d26697bd224d"},"headline":"Premio \u00abCompromiso con la Sostenibilidad en la Posventa\u00bb ANCERA","datePublished":"2024-12-18T13:01:48+00:00","dateModified":"2026-01-21T09:16:47+00:00","mainEntityOfPage":{"@id":"https:\/\/corporacionjimenezmana.com\/premio-compromiso-con-la-sostenibilidad-en-la-posventa-ancera\/"},"wordCount":214,"publisher":{"@id":"https:\/\/corporacionjimenezmana.com\/#organization"},"image":{"@id":"https:\/\/corporacionjimenezmana.com\/premio-compromiso-con-la-sostenibilidad-en-la-posventa-ancera\/#primaryimage"},"thumbnailUrl":"https:\/\/corporacionjimenezmana.com\/wp-content\/uploads\/2025\/01\/FOTO_FAMILIA_PREMIOS_COMPROMISO3.png","articleSection":["RSC"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/corporacionjimenezmana.com\/premio-compromiso-con-la-sostenibilidad-en-la-posventa-ancera\/","url":"https:\/\/corporacionjimenezmana.com\/premio-compromiso-con-la-sostenibilidad-en-la-posventa-ancera\/","name":"Premio \"Compromiso con la Sostenibilidad en la Posventa\" ANCERA - Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a","isPartOf":{"@id":"https:\/\/corporacionjimenezmana.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/corporacionjimenezmana.com\/premio-compromiso-con-la-sostenibilidad-en-la-posventa-ancera\/#primaryimage"},"image":{"@id":"https:\/\/corporacionjimenezmana.com\/premio-compromiso-con-la-sostenibilidad-en-la-posventa-ancera\/#primaryimage"},"thumbnailUrl":"https:\/\/corporacionjimenezmana.com\/wp-content\/uploads\/2025\/01\/FOTO_FAMILIA_PREMIOS_COMPROMISO3.png","datePublished":"2024-12-18T13:01:48+00:00","dateModified":"2026-01-21T09:16:47+00:00","breadcrumb":{"@id":"https:\/\/corporacionjimenezmana.com\/premio-compromiso-con-la-sostenibilidad-en-la-posventa-ancera\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/corporacionjimenezmana.com\/premio-compromiso-con-la-sostenibilidad-en-la-posventa-ancera\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/corporacionjimenezmana.com\/premio-compromiso-con-la-sostenibilidad-en-la-posventa-ancera\/#primaryimage","url":"https:\/\/corporacionjimenezmana.com\/wp-content\/uploads\/2025\/01\/FOTO_FAMILIA_PREMIOS_COMPROMISO3.png","contentUrl":"https:\/\/corporacionjimenezmana.com\/wp-content\/uploads\/2025\/01\/FOTO_FAMILIA_PREMIOS_COMPROMISO3.png","width":1500,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/corporacionjimenezmana.com\/premio-compromiso-con-la-sostenibilidad-en-la-posventa-ancera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/corporacionjimenezmana.com\/"},{"@type":"ListItem","position":2,"name":"Premio \u00abCompromiso con la Sostenibilidad en la Posventa\u00bb ANCERA"}]},{"@type":"WebSite","@id":"https:\/\/corporacionjimenezmana.com\/#website","url":"https:\/\/corporacionjimenezmana.com\/","name":"Jim\u00e9nez Ma\u00f1a Corporation","description":"Leading family business group in the distribution of vehicle spare parts. Since its foundation in 1936, it has demonstrated a great capacity for adaptation and growth, expanding its activities inside and outside the mobility sector, consolidating itself as a business group with multiple lines of business.","publisher":{"@id":"https:\/\/corporacionjimenezmana.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/corporacionjimenezmana.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/corporacionjimenezmana.com\/#organization","name":"Jim\u00e9nez Ma\u00f1a Corporation","url":"https:\/\/corporacionjimenezmana.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/corporacionjimenezmana.com\/#\/schema\/logo\/image\/","url":"https:\/\/corporacionjimenezmana.com\/wp-content\/uploads\/2024\/10\/imagotipo-Corporacion-Jimenez-Mana.svg","contentUrl":"https:\/\/corporacionjimenezmana.com\/wp-content\/uploads\/2024\/10\/imagotipo-Corporacion-Jimenez-Mana.svg","width":425,"height":94,"caption":"Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a"},"image":{"@id":"https:\/\/corporacionjimenezmana.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/corpjimenezmana\/?viewAsMember=true"]},{"@type":"Person","@id":"https:\/\/corporacionjimenezmana.com\/#\/schema\/person\/79f6bf54f1afc014ee30d26697bd224d","name":"Ana_CJM","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/e63e46543d6b7e0b7dc215b9d4a080da2328755463d201cae9932c5b21162524?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e63e46543d6b7e0b7dc215b9d4a080da2328755463d201cae9932c5b21162524?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e63e46543d6b7e0b7dc215b9d4a080da2328755463d201cae9932c5b21162524?s=96&d=mm&r=g","caption":"Ana_CJM"},"url":"https:\/\/corporacionjimenezmana.com\/en\/author\/ana_cjm\/"}]}},"_links":{"self":[{"href":"https:\/\/corporacionjimenezmana.com\/en\/wp-json\/wp\/v2\/posts\/1916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corporacionjimenezmana.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corporacionjimenezmana.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corporacionjimenezmana.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/corporacionjimenezmana.com\/en\/wp-json\/wp\/v2\/comments?post=1916"}],"version-history":[{"count":0,"href":"https:\/\/corporacionjimenezmana.com\/en\/wp-json\/wp\/v2\/posts\/1916\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corporacionjimenezmana.com\/en\/wp-json\/wp\/v2\/media\/1919"}],"wp:attachment":[{"href":"https:\/\/corporacionjimenezmana.com\/en\/wp-json\/wp\/v2\/media?parent=1916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corporacionjimenezmana.com\/en\/wp-json\/wp\/v2\/categories?post=1916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corporacionjimenezmana.com\/en\/wp-json\/wp\/v2\/tags?post=1916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}