{"id":1049,"date":"2025-01-21T09:45:41","date_gmt":"2025-01-21T09:45:41","guid":{"rendered":"https:\/\/peachpuff-snail-755067.hostingersite.com\/?post_type=historia&#038;p=1049"},"modified":"2026-02-20T07:06:06","modified_gmt":"2026-02-20T07:06:06","slug":"nacen-eurorecambios-del-camion-y-selling-motor","status":"publish","type":"historia","link":"https:\/\/corporacionjimenezmana.com\/en\/historia\/nacen-eurorecambios-del-camion-y-selling-motor\/","title":{"rendered":"Eurorecambios del Cami\u00f3n and Selling Motor are born"},"template":"","class_list":["post-1049","historia","type-historia","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nacen Eurorecambios del Cami\u00f3n y Selling Motor - Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/corporacionjimenezmana.com\/en\/history\/nacen-eurorecambios-del-camion-y-selling-motor\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nacen Eurorecambios del Cami\u00f3n y Selling Motor - Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/corporacionjimenezmana.com\/en\/history\/nacen-eurorecambios-del-camion-y-selling-motor\/\" \/>\n<meta property=\"og:site_name\" content=\"Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-20T07:06:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/historia\\\/nacen-eurorecambios-del-camion-y-selling-motor\\\/\",\"url\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/historia\\\/nacen-eurorecambios-del-camion-y-selling-motor\\\/\",\"name\":\"Nacen Eurorecambios del Cami\u00f3n y Selling Motor - Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/#website\"},\"datePublished\":\"2025-01-21T09:45:41+00:00\",\"dateModified\":\"2026-02-20T07:06:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/historia\\\/nacen-eurorecambios-del-camion-y-selling-motor\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/corporacionjimenezmana.com\\\/historia\\\/nacen-eurorecambios-del-camion-y-selling-motor\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/historia\\\/nacen-eurorecambios-del-camion-y-selling-motor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nacen Eurorecambios del Cami\u00f3n y Selling Motor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/#website\",\"url\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/\",\"name\":\"Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a\",\"description\":\"Grupo de empresas familiar l\u00edder en la distribuci\u00f3n de recambios de veh\u00edculos. Desde su fundaci\u00f3n en 1936, ha demostrado una gran capacidad de adaptaci\u00f3n y crecimiento, ampliando sus actividades dentro y fuera del sector de la movilidad, consolid\u00e1ndose como un grupo empresarial con m\u00faltiples l\u00edneas de negocio.\",\"publisher\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/#organization\",\"name\":\"Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a\",\"url\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/imagotipo-Corporacion-Jimenez-Mana.svg\",\"contentUrl\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/imagotipo-Corporacion-Jimenez-Mana.svg\",\"width\":425,\"height\":94,\"caption\":\"Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a\"},\"image\":{\"@id\":\"https:\\\/\\\/corporacionjimenezmana.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/corpjimenezmana\\\/?viewAsMember=true\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nacen Eurorecambios del Cami\u00f3n y Selling Motor - Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/corporacionjimenezmana.com\/en\/history\/nacen-eurorecambios-del-camion-y-selling-motor\/","og_locale":"en_GB","og_type":"article","og_title":"Nacen Eurorecambios del Cami\u00f3n y Selling Motor - Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a","og_url":"https:\/\/corporacionjimenezmana.com\/en\/history\/nacen-eurorecambios-del-camion-y-selling-motor\/","og_site_name":"Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a","article_modified_time":"2026-02-20T07:06:06+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/corporacionjimenezmana.com\/historia\/nacen-eurorecambios-del-camion-y-selling-motor\/","url":"https:\/\/corporacionjimenezmana.com\/historia\/nacen-eurorecambios-del-camion-y-selling-motor\/","name":"Nacen Eurorecambios del Cami\u00f3n y Selling Motor - Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a","isPartOf":{"@id":"https:\/\/corporacionjimenezmana.com\/#website"},"datePublished":"2025-01-21T09:45:41+00:00","dateModified":"2026-02-20T07:06:06+00:00","breadcrumb":{"@id":"https:\/\/corporacionjimenezmana.com\/historia\/nacen-eurorecambios-del-camion-y-selling-motor\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/corporacionjimenezmana.com\/historia\/nacen-eurorecambios-del-camion-y-selling-motor\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/corporacionjimenezmana.com\/historia\/nacen-eurorecambios-del-camion-y-selling-motor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/corporacionjimenezmana.com\/"},{"@type":"ListItem","position":2,"name":"Nacen Eurorecambios del Cami\u00f3n y Selling Motor"}]},{"@type":"WebSite","@id":"https:\/\/corporacionjimenezmana.com\/#website","url":"https:\/\/corporacionjimenezmana.com\/","name":"Jim\u00e9nez Ma\u00f1a Corporation","description":"Leading family business group in the distribution of vehicle spare parts. Since its foundation in 1936, it has demonstrated a great capacity for adaptation and growth, expanding its activities inside and outside the mobility sector, consolidating itself as a business group with multiple lines of business.","publisher":{"@id":"https:\/\/corporacionjimenezmana.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/corporacionjimenezmana.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/corporacionjimenezmana.com\/#organization","name":"Jim\u00e9nez Ma\u00f1a Corporation","url":"https:\/\/corporacionjimenezmana.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/corporacionjimenezmana.com\/#\/schema\/logo\/image\/","url":"https:\/\/corporacionjimenezmana.com\/wp-content\/uploads\/2024\/10\/imagotipo-Corporacion-Jimenez-Mana.svg","contentUrl":"https:\/\/corporacionjimenezmana.com\/wp-content\/uploads\/2024\/10\/imagotipo-Corporacion-Jimenez-Mana.svg","width":425,"height":94,"caption":"Corporaci\u00f3n Jim\u00e9nez Ma\u00f1a"},"image":{"@id":"https:\/\/corporacionjimenezmana.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/corpjimenezmana\/?viewAsMember=true"]}]}},"_links":{"self":[{"href":"https:\/\/corporacionjimenezmana.com\/en\/wp-json\/wp\/v2\/historia\/1049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corporacionjimenezmana.com\/en\/wp-json\/wp\/v2\/historia"}],"about":[{"href":"https:\/\/corporacionjimenezmana.com\/en\/wp-json\/wp\/v2\/types\/historia"}],"wp:attachment":[{"href":"https:\/\/corporacionjimenezmana.com\/en\/wp-json\/wp\/v2\/media?parent=1049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}